{"id":6910,"date":"2026-07-15T06:19:28","date_gmt":"2026-07-15T09:19:28","guid":{"rendered":"https:\/\/portaltvatosefatos.com.br\/?p=6910"},"modified":"2026-07-15T06:19:28","modified_gmt":"2026-07-15T09:19:28","slug":"inscricoes-abertas-para-o-processo-de-escolha-suplementar-e-emergencial-do-conselho-tutelar-de-nova-laranjeiras","status":"publish","type":"post","link":"https:\/\/portaltvatosefatos.com.br\/index.php\/2026\/07\/15\/inscricoes-abertas-para-o-processo-de-escolha-suplementar-e-emergencial-do-conselho-tutelar-de-nova-laranjeiras\/","title":{"rendered":"Inscri\u00e7\u00f5es abertas para o Processo de Escolha Suplementar e Emergencial do Conselho Tutelar de Nova Laranjeiras"},"content":{"rendered":"\n<p>O Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente (CMDCA) informa que estar\u00e3o abertas, de 15 a 25 de julho de 2026, as inscri\u00e7\u00f5es para o Processo de Escolha Suplementar e Emergencial destinado ao preenchimento de 2 vagas para Conselheiro Tutelar, al\u00e9m de suplentes.<\/p>\n\n\n\n<p>Podem participar os candidatos que atendam aos requisitos previstos no edital e apresentem toda a documenta\u00e7\u00e3o exigida.<\/p>\n\n\n\n<p>Per\u00edodo de inscri\u00e7\u00f5es: 15 a 25 de julho de 2026<\/p>\n\n\n\n<p>Local: Secretaria Municipal de Assist\u00eancia Social e A\u00e7\u00e3o Comunit\u00e1ria<\/p>\n\n\n\n<p>Data da elei\u00e7\u00e3o: 03 de setembro de 2026<\/p>\n\n\n\n<p>Entre os documentos exigidos est\u00e3o:<\/p>\n\n\n\n<p>RG e CPF;<\/p>\n\n\n\n<p>Comprovante de resid\u00eancia;<\/p>\n\n\n\n<p>T\u00edtulo de eleitor e comprovantes de vota\u00e7\u00e3o;<\/p>\n\n\n\n<p>Certid\u00f5es negativas c\u00edveis e criminais;<\/p>\n\n\n\n<p>Comprovante de escolaridade do ensino m\u00e9dio;<\/p>\n\n\n\n<p>Comprova\u00e7\u00e3o de experi\u00eancia na \u00e1rea da inf\u00e2ncia e juventude;<\/p>\n\n\n\n<p>Declara\u00e7\u00f5es previstas no edital;<\/p>\n\n\n\n<p>CNH categoria B ou superior.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Nova Laranjeiras. Cidade Viva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente (CMDCA) informa que estar\u00e3o abertas, de 15 a 25 de julho de 2026, as inscri\u00e7\u00f5es para o Processo de Escolha Suplementar e Emergencial destinado ao preenchimento de 2 vagas para Conselheiro Tutelar, al\u00e9m de suplentes. Podem participar os candidatos que atendam aos requisitos previstos no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[3,292],"tags":[],"_links":{"self":[{"href":"https:\/\/portaltvatosefatos.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6910"}],"collection":[{"href":"https:\/\/portaltvatosefatos.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaltvatosefatos.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaltvatosefatos.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaltvatosefatos.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6910"}],"version-history":[{"count":1,"href":"https:\/\/portaltvatosefatos.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6910\/revisions"}],"predecessor-version":[{"id":6912,"href":"https:\/\/portaltvatosefatos.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6910\/revisions\/6912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaltvatosefatos.com.br\/index.php\/wp-json\/wp\/v2\/media\/6911"}],"wp:attachment":[{"href":"https:\/\/portaltvatosefatos.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaltvatosefatos.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaltvatosefatos.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}